{"id":5902,"date":"2018-05-11T13:30:05","date_gmt":"2018-05-11T11:30:05","guid":{"rendered":"https:\/\/soib.es\/nou-proces-de-seleccio-del-soib-per-a-melia-hotels-international-a-mallorca\/"},"modified":"2018-05-15T12:59:17","modified_gmt":"2018-05-15T10:59:17","slug":"nuevo-proceso-de-seleccioon-del-soib-para-meliaa-hotels-international-en-mallorca","status":"publish","type":"post","link":"https:\/\/soib.es\/es\/nuevo-proceso-de-seleccioon-del-soib-para-meliaa-hotels-international-en-mallorca\/","title":{"rendered":"Nuevo proceso de seleccio\u0301n del SOIB para Melia\u0301 Hotels International en Mallorca"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; background_color=\u00bb#f7f7f7&#8243; _builder_version=\u00bb3.0.99&#8243; custom_padding=\u00bb25px|0px|25px|0px\u00bb][et_pb_row _builder_version=\u00bb3.0.99&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.99&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_text _builder_version=\u00bb3.0.99&#8243;]<\/p>\n<h1><strong>Nuevo proceso de seleccio\u0301n del SOIB para Melia\u0301 Hotels International en Mallorca<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb3.0.47&#8243; custom_padding=\u00bb25px|0px|54px|0px\u00bb][et_pb_row _builder_version=\u00bb3.0.99&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.99&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_text _builder_version=\u00bb3.0.99&#8243;]El <strong>SOIB Empresas<\/strong> ha organizado una nueva jornada de preseleccio\u0301n de personal para Melia\u0301 Hotels Internacional en Cales Mallorca que necesita cubrir 34 puestos de trabajo de los perfiles de cocina, bar-restaurante y pisos para la actual temporada turi\u0301stica.<\/p>\n<p>El proceso de seleccio\u0301n tendra\u0301 lugar el 22 de mayo, en la sala de ocio del espacio Na Camel\u00b7la en Manacor, y las entrevistas las hara\u0301n de manera conjunta el personal te\u0301cnico del servicio <strong>SOIB Empresas<\/strong> y de Melia\u0301. La cadena hotelera ofrece 12 puestos de cocina, 12 de bar-restaurante y 10 de pisos para los hoteles: <strong>Hotel Sol Cales de Mallorca, Hotel Sol Mirador de Cales y Hotel Sol Cala Antena<\/strong>.<\/p>\n<p>Las personas interesadas, que tienen que estar inscritas en el SOIB y cumplir con los requisitos de las ofertas, tienen que rellenar, hasta el 16 de mayo un formulario en li\u0301nia de la pa\u0301gina web del SOIB (<a style=\"font-size: 15px;\" href=\"https:\/\/soib.es\"><strong>www.soib.es<\/strong><\/a>). Esta prescripcio\u0301n y toda la informacio\u0301n sobre la tramitacio\u0301n que hay que hacer se puede consultar en: <a style=\"font-size: 15px;\" href=\"https:\/\/bit.ly\/2GSUfBI\"><strong>https:\/\/bit.ly\/2GSUfBI<\/strong><\/a>. Al acabar el proceso de seleccio\u0301n, SOIB Empresas remitira\u0301 una lista u\u0301nica a Melia\u0301 para que haga la seleccio\u0301n final.<\/p>\n<p>Este an\u0303o, el SOIB ya ha participado en 2 procesos de seleccio\u0301n para Melia\u0301, concretamente para cubrir 54 puestos de trabajo de los hoteles ubicados en la zona de Calvia\u0300 a los que se han presentado <strong>ma\u0301s de 90 candidatos<\/strong>. Adema\u0301s, el mes pasado, el <strong>SOIB en Menorca<\/strong> gestiono\u0301 la seleccio\u0301n de 68 lugares de trabajo y el <strong>SOIB en Eivissa<\/strong> preselecciono\u0301 11. Por lo tanto, la suma de los 4 jobs days permitira\u0301 escoger 167 puestos de trabajo para esta cadena hotelera en las tres islas.<\/p>\n<p>El an\u0303o 2017 se llevaron a cabo un total de 5 job days para Melia\u0301 Hotels International, 3 para hoteles de Mallorca, y el resto en Menorca y Eivissa, para cubrir me\u0301s de 130 puestos de trabajo y este an\u0303o ha incrementado la oferta en 37 ma\u0301s. En el marco del proyecto de transformacio\u0301n de su oferta hotelera, la compan\u0303i\u0301a sigue aumentando la plantilla para hoteles nuevos y de otros que han sido reposicionados.<\/p>\n<p>En concreto, este an\u0303o ya se han llevado a cabo <strong>21 jornadas de seleccio\u0301n para empresas<\/strong> de Balears. Durante estos meses se han organizado 13 job days para los grupos hoteleros Iberostar, Be Live Hoteles, Melia\u0301, Thomas Cook, Garden Hotels y 8, para cadenas de supermercados de alimentacio\u0301n como Mercadona, Eroski y Carrefour.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; background_color=\u00bb#df1f4f\u00bb disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb3.0.82&#8243; custom_padding=\u00bb54px|0px|0px|0px\u00bb][et_pb_row custom_padding=\u00bb0px|0px|27px|0px\u00bb custom_css_main_2=\u00bbmargin-left: -20%;\u00bb custom_css_main_3=\u00bbmargin-left: 32px;\u00bb custom_css_main_4=\u00bbmargin-left: 100px;\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_blurb url=\u00bbhttps:\/\/twitter.com\/soibinfo?lang=es\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%292%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb use_icon_font_size=\u00bbon\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb custom_css_main=\u00bbmargin-left: -20%;\u00bb][et_pb_blurb url=\u00bbhttps:\/\/www.facebook.com\/SOIBINFO\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%291%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb custom_css_main=\u00bbmargin-left: 32px;\u00bb][et_pb_image src=\u00bbhttps:\/\/soib.es\/wp-content\/uploads\/2017\/10\/ue3.gif\u00bb _builder_version=\u00bb3.0.82&#8243; module_alignment=\u00bbleft\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb custom_css_main=\u00bbmargin-left: 100px;\u00bb][et_pb_text _builder_version=\u00bb3.0.82&#8243; custom_css_main_element=\u00bbwidth: 150%;\u00bb]<\/p>\n<p style=\"color: #fff; text-align: right;\">Servicio de Ocupaci\u00f3n de las Islas Baleares (SOIB):<\/p>\n<p style=\"color: #fff; text-align: right;\">Cam\u00ed vell de Bunyola, 43, 1\u00ba &#8211; Edificio rotonda Asima<\/p>\n<p style=\"color: #fff; text-align: right;\">Pol\u00edgono de son Castell\u00f3 &#8211; 07009 Palma<\/p>\n<p style=\"color: #fff; text-align: right;\">Tel\u00e9fono <a style=\"color: #fff;\" href=\"tel:+34971784991\">971784991<\/a> &#8211; Fax 971784942<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; background_color=\u00bb#df1f4f\u00bb disabled_on=\u00bbon|off|on\u00bb _builder_version=\u00bb3.0.82&#8243; custom_padding=\u00bb20px|0px|0px|0px\u00bb][et_pb_row custom_padding=\u00bb0px|0px|27px|0px\u00bb custom_css_main_2=\u00bbmargin-left: -225px;\u00bb custom_css_main_3=\u00bbmargin-left: 32px;\u00bb custom_css_main_4=\u00bbmargin-left: 100px;\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_text _builder_version=\u00bb3.0.82&#8243; custom_css_main_element=\u00bbwidth: 150%;\u00bb]<\/p>\n<p style=\"color: #fff;\">Servicio de Ocupaci\u00f3n de las Islas Baleares (SOIB):<\/p>\n<p style=\"color: #fff;\">Cam\u00ed vell de Bunyola, 43, 1\u00ba &#8211; Edificio rotonda Asima<\/p>\n<p style=\"color: #fff;\">Pol\u00edgono de son Castell\u00f3 &#8211; 07009 Palma<\/p>\n<p style=\"color: #fff;\">Tel\u00e9fono <a style=\"color: #fff;\" href=\"tel:+34971784991\">971784991<\/a> &#8211; Fax 971784942<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/soib.es\/wp-content\/uploads\/2017\/10\/ue3.gif\u00bb _builder_version=\u00bb3.0.82&#8243; max_width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb][\/et_pb_image][et_pb_blurb url=\u00bbhttps:\/\/twitter.com\/soibinfo?lang=es\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%292%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb use_icon_font_size=\u00bbon\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb custom_css_main_element=\u00bbfloat: right;\u00bb][\/et_pb_blurb][et_pb_blurb url=\u00bbhttps:\/\/www.facebook.com\/SOIBINFO\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%291%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; background_color=\u00bb#df1f4f\u00bb disabled_on=\u00bboff|on|on\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_row custom_padding=\u00bb15px|0px|0px|0px\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_text _builder_version=\u00bb3.0.82&#8243;]<\/p>\n<p style=\"color: #fff;\">Servicio de Ocupaci\u00f3n de las Islas Baleares (SOIB):<\/p>\n<p style=\"color: #fff;\">Cam\u00ed Vell de Bunyola, 43, 1\u00aa &#8211; edificio rotonda Asima<\/p>\n<p style=\"color: #fff;\">Pol\u00edgono de son Castell\u00f3 &#8211; 07009 Palma<\/p>\n<p style=\"color: #fff;\">Tel\u00e9fono 971784991 &#8211; Fax 971784942<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=\u00bb15px|0px|0px|0px\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_image src=\u00bbhttps:\/\/soib.es\/wp-content\/uploads\/2017\/10\/ue3.gif\u00bb _builder_version=\u00bb3.0.82&#8243; max_width=\u00bb50%\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding=\u00bb0px|0px|0px|0px\u00bb _builder_version=\u00bb3.0.82&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.0.82&#8243; parallax=\u00bboff\u00bb parallax_method=\u00bbon\u00bb][et_pb_blurb url=\u00bbhttps:\/\/www.facebook.com\/SOIBINFO\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%291%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb][\/et_pb_blurb][et_pb_blurb url=\u00bbhttps:\/\/twitter.com\/soibinfo?lang=es\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb%%292%%\u00bb icon_color=\u00bb#df1f4f\u00bb use_circle=\u00bbon\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb3.0.82&#8243; animation=\u00bboff\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo proceso de seleccio\u0301n del SOIB para Melia\u0301 Hotels International en Mallorca El SOIB Empresas ha organizado una nueva jornada de preseleccio\u0301n de personal para Melia\u0301 Hotels Internacional en Cales Mallorca que necesita cubrir 34 puestos de trabajo de los perfiles de cocina, bar-restaurante y pisos para la actual temporada turi\u0301stica. El proceso de seleccio\u0301n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[188],"tags":[],"class_list":["post-5902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_featured_media_url":"https:\/\/soib.es\/wp-content\/uploads\/2018\/05\/melia-hotels.png","jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 09:31:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts\/5902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/comments?post=5902"}],"version-history":[{"count":0,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts\/5902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/media\/5891"}],"wp:attachment":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/media?parent=5902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/categories?post=5902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/tags?post=5902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}