{"id":11746,"date":"2019-03-26T15:55:15","date_gmt":"2019-03-26T14:55:15","guid":{"rendered":"https:\/\/soib.es\/?p=11746"},"modified":"2019-04-08T09:00:29","modified_gmt":"2019-04-08T07:00:29","slug":"40-personas-mayores-de-30-anos-empiezan-un-contrato-de-formacion-y-aprendizaje-en-inca-gracias-al-programa-soib-30-formacion-y-ocupacion","status":"publish","type":"post","link":"https:\/\/soib.es\/es\/40-personas-mayores-de-30-anos-empiezan-un-contrato-de-formacion-y-aprendizaje-en-inca-gracias-al-programa-soib-30-formacion-y-ocupacion\/","title":{"rendered":"40 personas, mayores de 30 a\u00f1os, empiezan un contrato de formaci\u00f3n y aprendizaje en Inca gracias al programa SOIB 30 Formaci\u00f3n y Ocupaci\u00f3n"},"content":{"rendered":"<p>El Centro de Formaci\u00f3n de Inca ha acogido hoy el acto de bienvenida a los alumnos de los cuatro programas <strong>SOIB 30 Formaci\u00f3n y Ocupaci\u00f3n <\/strong>para mayores de 30 a\u00f1os. El alcalde Virgilio Moreno, la concejala de Formaci\u00f3n y Educaci\u00f3n, Alice Weber y el director del SOIB, Pere Torrens, han saludado a los 40 alumnos-trabajadores que durante un a\u00f1o conseguir\u00e1n un certificado de profesionalidad mediante formaci\u00f3n y ocupaci\u00f3n. En los cuatro proyectos se han invertido 814.826 \u20ac, financiados por la Conferencia Sectorial de Empleo y Asuntos Laborales, con la participaci\u00f3n del SOIB.<\/p>\n<p><strong>\u00abInca Connecta\u00bb<\/strong> llega a su tercera edici\u00f3n y forma personas desocupadas para desarrollar tareas de mantenimiento de instalaciones hoteleras y alojamientos, aportando polivalencia y capacidad para realizar reparaciones de diferente tipo. De esta manera, el alumno-trabajador alcanza conocimientos de electricidad, telecomunicaciones, fontaner\u00eda, calefacci\u00f3n y climatizaci\u00f3n. Hay que se\u00f1alar que en el periodo formativo se colaborar\u00e1 en las reparaciones en diferentes inmuebles p\u00fablicos. El presupuesto es de 203.958\u20ac. Se imparte el certificado de profesionalidad de nivel 1 Operaciones auxiliares de montaje de instalaciones electrot\u00e9cnicas y de comunicaciones en edificios.<\/p>\n<p><strong>\u201cInca<\/strong><strong> en Red\u201d e \u201cInca Digital <\/strong>4.0\u201d calificar\u00e1 los alumnos para llevar a cabo tareas de recepci\u00f3n b\u00e1sicas en hoteles, servicios de atenci\u00f3n al cliente y trabajos administrativos (archivar, escanear, digitalizar&#8230;) Adem\u00e1s, en el segundo de ellos, la formaci\u00f3n se completa con conocimientos de atenci\u00f3n al cliente y de lengua inglesa. Realizar\u00e1n tareas de informaci\u00f3n, digitalizaci\u00f3n de documentaci\u00f3n municipal y ejecutar\u00e1n encuestas de satisfacci\u00f3n, entre otros trabajos. El presupuesto sube a 199.484 \u20ac y\u00a0 202.395 \u20ac respectivamente. En ambos programas se imparte el certificado de nivel 1 Operaciones de grabaci\u00f3n y tratamiento de datos y documentos.<\/p>\n<p>Por \u00faltimo, \u201c<strong>Es Rosset\u201d<\/strong> tiene como finalidad mejorar y dotar de nuevas estructuras las instalaciones municipales y educativas con elementos de carpinter\u00eda y mueble. El presupuesto es de 208.988 \u20ac. Se impartir\u00e1 el certificado de profesionalidad de nivel 2 de instalaci\u00f3n de elementos de carpinter\u00eda.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Formaci\u00f3n de Inca ha acogido hoy el acto de bienvenida a los alumnos de los cuatro programas SOIB 30 Formaci\u00f3n y Ocupaci\u00f3n para mayores de 30 a\u00f1os. El alcalde Virgilio Moreno, la concejala de Formaci\u00f3n y Educaci\u00f3n, Alice Weber y el director del SOIB, Pere Torrens, han saludado a los 40 alumnos-trabajadores [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":11740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[188],"tags":[],"class_list":["post-11746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:35:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts\/11746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/comments?post=11746"}],"version-history":[{"count":0,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/posts\/11746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/media\/11740"}],"wp:attachment":[{"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/media?parent=11746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/categories?post=11746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soib.es\/es\/wp-json\/wp\/v2\/tags?post=11746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}